{"id":17763,"date":"2025-04-08T15:21:50","date_gmt":"2025-04-08T13:21:50","guid":{"rendered":"https:\/\/science-teaching.org\/?p=17763"},"modified":"2025-12-15T10:29:40","modified_gmt":"2025-12-15T09:29:40","slug":"como-aprendemos-a-leer","status":"publish","type":"post","link":"https:\/\/science-teaching.org\/es\/libros\/como-aprendemos-a-leer","title":{"rendered":"\u00bfC\u00f3mo aprendemos a leer?"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-text-align-center has-x-large-font-size\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#0071a1\" class=\"has-inline-color\">\u00bfC\u00f3mo aprendemos a leer?<\/mark><br>Y c\u00f3mo ense\u00f1ar a leer seg\u00fan la ciencia<\/h1>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:22px\">Aprender a leer constituye un reto cognitivo extraordinario. Comprender el modo en que nuestra mente es capaz de lograrlo puede ayudarnos a orientar la ense\u00f1anza de la lectura para contribuir al desarrollo de esta competencia esencial.<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"postdate-to-change has-cyan-bluish-gray-color has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"font-size:15px\">8 de abril de 2025<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1.jpg\" alt=\"\" class=\"wp-image-17767\" srcset=\"https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1.jpg 1920w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1-300x169.jpg 300w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1-1024x576.jpg 1024w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1-768x432.jpg 768w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1-1536x864.jpg 1536w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/como-aprendemos-a-leer-1920x1080-1-700x394.jpg 700w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\">En su nuevo libro, <em>\u00bfC\u00f3mo aprendemos a leer?<\/em>, <strong>H\u00e9ctor Ruiz Mart\u00edn recorre los fundamentos cient\u00edficos del aprendizaje lector<\/strong> y ofrece una gu\u00eda clara, estructurada y rigurosa para docentes y profesionales de la educaci\u00f3n que deseen basar su pr\u00e1ctica en lo que sugiere la evidencia cient\u00edfica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\">A lo largo de sus cinco bloques tem\u00e1ticos, el autor \u2014director de la International Science Teaching Foundation e investigador en psicolog\u00eda cognitiva del aprendizaje y la memoria\u2014 explora conceptos clave como <strong>los factores que influyen en la motivaci\u00f3n por leer, las etapas de la descodificaci\u00f3n, las bases de la comprensi\u00f3n ling\u00fc\u00edstica, las estrategias did\u00e1cticas m\u00e1s eficaces y las dificultades comunes como la dislexia<\/strong>. Adem\u00e1s, dedica un cap\u00edtulo entero a desmontar mitos y pr\u00e1cticas pseudocient\u00edficas que todav\u00eda persisten en la ense\u00f1anza de la lectura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\">Con un estilo accesible y directo, pero sin renunciar al rigor, <em>\u00bfC\u00f3mo aprendemos a leer?<\/em> resume lo que las ciencias cognitivas han descubierto sobre ense\u00f1ar a leer y lo traduce en orientaciones pr\u00e1cticas para el aula. Se trata, as\u00ed, de <strong>una herramienta valiosa para quienes buscan mejorar la ense\u00f1anza de la lectura vali\u00e9ndose de las aportaciones de la ciencia.<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Aprender a leer<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\">Un texto introductorio, ameno y accesible sobre qu\u00e9 nos dice la ciencia acerca de c\u00f3mo aprendemos a leer, y sobre qu\u00e9 podemos hacer para ense\u00f1ar a leer bas\u00e1ndonos en estos principios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\">La investigaci\u00f3n en psicolog\u00eda y neurociencia lleva d\u00e9cadas acumulando evidencias sobre c\u00f3mo aprendemos a leer y sobre qu\u00e9 m\u00e9todos de ense\u00f1anza son los m\u00e1s prometedores para no dejar a ning\u00fan ni\u00f1o atr\u00e1s en el desarrollo de esta habilidad tan fundamental para la vida.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:65%\">\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-dots\"\/>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:24px\"><strong>Este libro pretende sintetizar todo este conocimiento y acercarlo de un modo ameno, comprensible y pr\u00e1ctico a quienes se enfrentan a diario al reto de ense\u00f1ar a leer, con la intenci\u00f3n de ayudarles en tan encomiable misi\u00f3n.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-dots\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/portada-2-como-aprendemos-a-leer-es.jpg\" alt=\"\u00bfC\u00f3mo aprendemos a leer?\" class=\"wp-image-17787\" style=\"width:300px\" srcset=\"https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/portada-2-como-aprendemos-a-leer-es.jpg 400w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/portada-2-como-aprendemos-a-leer-es-300x300.jpg 300w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/portada-2-como-aprendemos-a-leer-es-150x150.jpg 150w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/portada-2-como-aprendemos-a-leer-es-120x120.jpg 120w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/portada-2-como-aprendemos-a-leer-es-125x125.jpg 125w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#abb7c217\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<h3 class=\"wp-block-heading\">Sobre el autor<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\"><strong>H\u00e9ctor Ruiz Mart\u00edn<\/strong> es el director de la International Science Teaching Foundation, investigador y divulgador especializado en la neurociencia y la <strong>psicolog\u00eda cognitiva de la memoria y el aprendizaje<\/strong>, con un especial inter\u00e9s en su aplicaci\u00f3n a los contextos educativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:19px\">En los \u00faltimos a\u00f1os ha trabajado en el dise\u00f1o de materiales did\u00e1cticos basados en la investigaci\u00f3n sobre c\u00f3mo aprenden las personas. Es tambi\u00e9n autor de los libros <em><a href=\"https:\/\/science-teaching.org\/es\/libros\/edumitos-ideas-sobre-el-aprendizaje-sin-respaldo-cientifico\">\u00abEdumitos\u00bb. Ideas sobre el aprendizaje sin respaldo cient\u00edfico<\/a><\/em>, <em><a href=\"https:\/\/science-teaching.org\/es\/libros\/libro-conoce-tu-cerebro-para-aprender-a-aprender\">Conoce tu cerebro para aprender a aprender<\/a><\/em>, <em><a href=\"https:\/\/science-teaching.org\/es\/libros\/aprendiendo-a-aprender\">Aprendiendo a aprender<\/a> <\/em>y <em><a href=\"https:\/\/science-teaching.org\/es\/libros\/libro-como-aprendemos\">\u00bfC\u00f3mo aprendemos?<\/a><\/em>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/science-teaching.org\/es\/investigacion\/promover-desarrollo-cognitivo-ninos-y-ninas\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2.jpg\" alt=\"Promover el desarrollo cognitivo de los m\u00e1s peque\u00f1os\" class=\"wp-image-17836\" style=\"width:350px\" srcset=\"https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2.jpg 1080w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-300x300.jpg 300w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-1024x1024.jpg 1024w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-150x150.jpg 150w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-768x768.jpg 768w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-525x525.jpg 525w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-120x120.jpg 120w, https:\/\/science-teaching.org\/wp-content\/uploads\/2025\/04\/xxss-leer-historias-2-125x125.jpg 125w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/a><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<hr class=\"wp-block-separator has-text-color has-cyan-bluish-gray-color has-alpha-channel-opacity has-cyan-bluish-gray-background-color has-background is-style-wide\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:16px\"><strong>T\u00edtulo del libro: <\/strong><em>\u00bfC\u00f3mo aprendemos a leer? Y c\u00f3mo ense\u00f1ar a leer seg\u00fan la ciencia.<\/em><br><strong>Autor:<\/strong> H\u00e9ctor Ruiz Mart\u00edn<br><strong>ISBN:<\/strong> 979-13-990185-1-6<br><strong>Editorial:<\/strong> International Science Teaching Foundation<br><strong>Lengua del libro: <\/strong>Espa\u00f1ol<br><strong>N\u00famero de p\u00e1ginas: <\/strong>380 p\u00e1ginas<br><strong>Fecha de publicaci\u00f3n:<\/strong>  Abril de 2025<\/p>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Opciones de compra <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#0071a1\" class=\"has-inline-color\"><strong>\u00a1Pregunta en tu librer\u00eda!<\/strong><\/mark><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-63375db1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.amazon.es\/%C2%BFC%C3%B3mo-aprendemos-leer-ense%C3%B1ar-ciencia\/dp\/B0F4MFDB1G\/ref=sr_1_1?__mk_es_ES=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=3DWKFNRY48JNS&amp;dib=eyJ2IjoiMSJ9.8SeaLsb8gi25zLzcppK5FXPgAek3myl9dfyG_eV9DInUGKL7J5AQmnJv-WiTn6xP-HCB4lv9JbunqJhcu5iVatQV9tdTzPxBwkcZ2_pw4S_rpl3foRx7dKCiTRQn9UsLxyb8kM9aH1rOXS20ZZqG672u_45G50qs7uF2ZDoLCC0nkJ9L7zTLIXt0xwgJ0YTTgU7knFfdvhpcapicRvPNU_3QrFsdcLi7o-f3Ciuvh6kKulESKKrtxVb2ywdiXN24xlEPPvvXhHP8QJMf7SxNdWh0PMV3h5By-GFvQ4gyINI.zMp826d16qSq_OBnqIxPKsSkoLODXEv28Sse4oSvg1Q&amp;dib_tag=se&amp;keywords=libro+como+aprendemos+a+leer&amp;qid=1744562610&amp;sprefix=libro+como+aprendemos+a+leer%2Caps%2C104&amp;sr=8-1\" style=\"background-color:#0071a1\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Amazon<\/strong> (Espa\u00f1a)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.amazon.com.mx\/%C2%BFC%C3%B3mo-aprendemos-leer-ense%C3%B1ar-ciencia\/dp\/B0F4MFDB1G\/ref=sr_1_1?__mk_es_MX=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=1R7MBX2UVN2XP&amp;dib=eyJ2IjoiMSJ9.7DvCAvaPOkdsiGmwqEEpKtSgYl4IfXkEIg4w7BBM5I7IcotsN53hH-ZDJir9pmO6KNnY4z0ggNebJu2hUdV7NFjBpAY2ANsMK_t3Xz-C_1-BZArPmsB6XD5pSTkSBV-4YxLS729SzYMCb6J7dF0Dpa5U8G8zNuHRmhtpsYhGSgYum-_RX6ouMLY2K24kvFPO0lpUKjcrN4kWs4KgbF6HibD-3-fCICb2o7rVirfauwi-VhBzAA5sMOQtUAa3bhtlrOZh7Wbq6uWE-9O9mSWzwjo-ZvbJ_WftTdZt-atjYNc.SV4C-EbvzR5Mj4MNWeAJmdHvCO0S8W7jrtacX4ikkzs&amp;dib_tag=se&amp;keywords=como+ense%C3%B1ar+a+leer&amp;qid=1745319918&amp;sprefix=como+ense%C3%B1ar+a+leer%2Caps%2C243&amp;sr=8-1&amp;ufe=app_do%3Aamzn1.fos.de93fa6a-174c-4df7-be7c-5bc8e9c5a71b\" style=\"background-color:#0071a1\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Amazon<\/strong> (M\u00e9xico)<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/science-teaching.org\/ca\/llibres\/com-aprenem-a-llegir\" style=\"background-color:#0071a1\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Versi\u00f3n en catal\u00e1n<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Distribuidores<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-63375db1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfI1RqhSxZf_98ZttOqqF-GXipwEeXuzbWpRQkxMtWErHPZRg\/viewform?usp=preview\" style=\"background-color:#0071a1\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Escuelas<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/arcobaleno.es\/es\/articles\/145930\" style=\"background-color:#0071a1\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Librer\u00edas<\/strong> (Europa y Australia)<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo libro de H\u00e9ctor Ruiz Mart\u00edn es una gu\u00eda esencial para maestros que quieren ense\u00f1ar a leer con base en la evidencia cient\u00edfica.<\/p>\n","protected":false},"author":2,"featured_media":17767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[462],"tags":[1183,1130,934,1208,1381,1380,1225,1211,1227,1379,925,916,918,1212],"class_list":["post-17763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libros","tag-aprender","tag-aprendizaje","tag-cerebro","tag-cognicion","tag-cursos-en-linea","tag-cursos-online","tag-ensenar","tag-evidencia-cientifica","tag-formacion-al-profesorado","tag-formacion-reconocida","tag-hector-ruiz-martin","tag-lectura","tag-leer","tag-psicologia-cognitiva"],"_links":{"self":[{"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/posts\/17763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/comments?post=17763"}],"version-history":[{"count":83,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/posts\/17763\/revisions"}],"predecessor-version":[{"id":19518,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/posts\/17763\/revisions\/19518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/media\/17767"}],"wp:attachment":[{"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/media?parent=17763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/categories?post=17763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/science-teaching.org\/es\/wp-json\/wp\/v2\/tags?post=17763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}